{"id":7931,"date":"2021-10-17T21:12:44","date_gmt":"2021-10-17T19:12:44","guid":{"rendered":"https:\/\/www.feuerwehr-daun.de\/wp\/?p=7931"},"modified":"2021-10-23T09:42:04","modified_gmt":"2021-10-23T07:42:04","slug":"einsatz-231-2021-besetzung-fez","status":"publish","type":"post","link":"https:\/\/www.feuerwehr-daun.de\/wp\/einsatz-231-2021-besetzung-fez\/","title":{"rendered":"Einsatz 234\/2021: Besetzung FEZ"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Am 16.10.2021 wurde die Feuerwehr Daun um 23.40 Uhr alarmiert, um die&nbsp;<a href=\"https:\/\/www.feuerwehr-daun.de\/wp\/feuerwehr\/feuerwehrhaus\/feuerwehreinsatzzentrale\/\">FEZ<\/a>&nbsp;f\u00fcr die Feuerwehr \u00dcdersdorf zu besetzen. Diese wurde zu einem M\u00fcllbrand in \u00dcdersdorf alarmiert.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am 16.10.2021 wurde die Feuerwehr Daun um 23.40 Uhr alarmiert, um die&nbsp;FEZ&nbsp;f\u00fcr die Feuerwehr \u00dcdersdorf zu besetzen. Diese wurde zu einem M\u00fcllbrand in \u00dcdersdorf alarmiert.<\/p>\n","protected":false},"author":16,"featured_media":4567,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"yes","footnotes":""},"categories":[1,5,71,65],"tags":[],"class_list":["post-7931","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","category-einsatze","category-einsaetze-2021","category-fez"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Einsatz 234\/2021: Besetzung FEZ - Freiwillige Feuerwehr Daun<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.feuerwehr-daun.de\/wp\/einsatz-231-2021-besetzung-fez\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Einsatz 234\/2021: Besetzung FEZ - Freiwillige Feuerwehr Daun\" \/>\n<meta property=\"og:description\" content=\"Am 16.10.2021 wurde die Feuerwehr Daun um 23.40 Uhr alarmiert, um die&nbsp;FEZ&nbsp;f\u00fcr die Feuerwehr \u00dcdersdorf zu besetzen. Diese wurde zu einem M\u00fcllbrand in \u00dcdersdorf alarmiert.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.feuerwehr-daun.de\/wp\/einsatz-231-2021-besetzung-fez\/\" \/>\n<meta property=\"og:site_name\" content=\"Freiwillige Feuerwehr Daun\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/feuerwehr.daun\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-17T19:12:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-23T07:42:04+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.feuerwehr-daun.de\/wp\/wp-content\/uploads\/2019\/02\/FEZ-Daun-a.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"FEZ Daun\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Feuerwehr_Daun\" \/>\n<meta name=\"twitter:site\" content=\"@Feuerwehr_Daun\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"FEZ Daun\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.feuerwehr-daun.de\\\/wp\\\/einsatz-231-2021-besetzung-fez\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.feuerwehr-daun.de\\\/wp\\\/einsatz-231-2021-besetzung-fez\\\/\"},\"author\":{\"name\":\"FEZ Daun\",\"@id\":\"http:\\\/\\\/www.feuerwehr-daun.de\\\/wp\\\/#\\\/schema\\\/person\\\/d2155f4754f9c8bbdc07fe7e0850e96e\"},\"headline\":\"Einsatz 234\\\/2021: Besetzung FEZ\",\"datePublished\":\"2021-10-17T19:12:44+00:00\",\"dateModified\":\"2021-10-23T07:42:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.feuerwehr-daun.de\\\/wp\\\/einsatz-231-2021-besetzung-fez\\\/\"},\"wordCount\":32,\"image\":{\"@id\":\"http:\\\/\\\/www.feuerwehr-daun.de\\\/wp\\\/einsatz-231-2021-besetzung-fez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.feuerwehr-daun.de\\\/wp\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/FEZ-Daun-a.jpg\",\"articleSection\":[\"Aktuelles\",\"Eins\u00e4tze\",\"Eins\u00e4tze 2021\",\"FEZ\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.feuerwehr-daun.de\\\/wp\\\/einsatz-231-2021-besetzung-fez\\\/\",\"url\":\"http:\\\/\\\/www.feuerwehr-daun.de\\\/wp\\\/einsatz-231-2021-besetzung-fez\\\/\",\"name\":\"Einsatz 234\\\/2021: Besetzung FEZ - Freiwillige Feuerwehr Daun\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.feuerwehr-daun.de\\\/wp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.feuerwehr-daun.de\\\/wp\\\/einsatz-231-2021-besetzung-fez\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.feuerwehr-daun.de\\\/wp\\\/einsatz-231-2021-besetzung-fez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.feuerwehr-daun.de\\\/wp\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/FEZ-Daun-a.jpg\",\"datePublished\":\"2021-10-17T19:12:44+00:00\",\"dateModified\":\"2021-10-23T07:42:04+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/www.feuerwehr-daun.de\\\/wp\\\/#\\\/schema\\\/person\\\/d2155f4754f9c8bbdc07fe7e0850e96e\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.feuerwehr-daun.de\\\/wp\\\/einsatz-231-2021-besetzung-fez\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.feuerwehr-daun.de\\\/wp\\\/einsatz-231-2021-besetzung-fez\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"http:\\\/\\\/www.feuerwehr-daun.de\\\/wp\\\/einsatz-231-2021-besetzung-fez\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.feuerwehr-daun.de\\\/wp\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/FEZ-Daun-a.jpg\",\"contentUrl\":\"https:\\\/\\\/www.feuerwehr-daun.de\\\/wp\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/FEZ-Daun-a.jpg\",\"width\":900,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.feuerwehr-daun.de\\\/wp\\\/einsatz-231-2021-besetzung-fez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/www.feuerwehr-daun.de\\\/wp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Einsatz 234\\\/2021: Besetzung FEZ\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.feuerwehr-daun.de\\\/wp\\\/#website\",\"url\":\"http:\\\/\\\/www.feuerwehr-daun.de\\\/wp\\\/\",\"name\":\"Freiwillige Feuerwehr Daun\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.feuerwehr-daun.de\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/www.feuerwehr-daun.de\\\/wp\\\/#\\\/schema\\\/person\\\/d2155f4754f9c8bbdc07fe7e0850e96e\",\"name\":\"FEZ Daun\",\"url\":\"https:\\\/\\\/www.feuerwehr-daun.de\\\/wp\\\/author\\\/fez-daun\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Einsatz 234\/2021: Besetzung FEZ - Freiwillige Feuerwehr Daun","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.feuerwehr-daun.de\/wp\/einsatz-231-2021-besetzung-fez\/","og_locale":"de_DE","og_type":"article","og_title":"Einsatz 234\/2021: Besetzung FEZ - Freiwillige Feuerwehr Daun","og_description":"Am 16.10.2021 wurde die Feuerwehr Daun um 23.40 Uhr alarmiert, um die&nbsp;FEZ&nbsp;f\u00fcr die Feuerwehr \u00dcdersdorf zu besetzen. Diese wurde zu einem M\u00fcllbrand in \u00dcdersdorf alarmiert.","og_url":"http:\/\/www.feuerwehr-daun.de\/wp\/einsatz-231-2021-besetzung-fez\/","og_site_name":"Freiwillige Feuerwehr Daun","article_publisher":"http:\/\/www.facebook.com\/feuerwehr.daun\/","article_published_time":"2021-10-17T19:12:44+00:00","article_modified_time":"2021-10-23T07:42:04+00:00","og_image":[{"width":900,"height":400,"url":"http:\/\/www.feuerwehr-daun.de\/wp\/wp-content\/uploads\/2019\/02\/FEZ-Daun-a.jpg","type":"image\/jpeg"}],"author":"FEZ Daun","twitter_card":"summary_large_image","twitter_creator":"@Feuerwehr_Daun","twitter_site":"@Feuerwehr_Daun","twitter_misc":{"Verfasst von":"FEZ Daun","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.feuerwehr-daun.de\/wp\/einsatz-231-2021-besetzung-fez\/#article","isPartOf":{"@id":"http:\/\/www.feuerwehr-daun.de\/wp\/einsatz-231-2021-besetzung-fez\/"},"author":{"name":"FEZ Daun","@id":"http:\/\/www.feuerwehr-daun.de\/wp\/#\/schema\/person\/d2155f4754f9c8bbdc07fe7e0850e96e"},"headline":"Einsatz 234\/2021: Besetzung FEZ","datePublished":"2021-10-17T19:12:44+00:00","dateModified":"2021-10-23T07:42:04+00:00","mainEntityOfPage":{"@id":"http:\/\/www.feuerwehr-daun.de\/wp\/einsatz-231-2021-besetzung-fez\/"},"wordCount":32,"image":{"@id":"http:\/\/www.feuerwehr-daun.de\/wp\/einsatz-231-2021-besetzung-fez\/#primaryimage"},"thumbnailUrl":"https:\/\/www.feuerwehr-daun.de\/wp\/wp-content\/uploads\/2019\/02\/FEZ-Daun-a.jpg","articleSection":["Aktuelles","Eins\u00e4tze","Eins\u00e4tze 2021","FEZ"],"inLanguage":"de"},{"@type":"WebPage","@id":"http:\/\/www.feuerwehr-daun.de\/wp\/einsatz-231-2021-besetzung-fez\/","url":"http:\/\/www.feuerwehr-daun.de\/wp\/einsatz-231-2021-besetzung-fez\/","name":"Einsatz 234\/2021: Besetzung FEZ - Freiwillige Feuerwehr Daun","isPartOf":{"@id":"http:\/\/www.feuerwehr-daun.de\/wp\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.feuerwehr-daun.de\/wp\/einsatz-231-2021-besetzung-fez\/#primaryimage"},"image":{"@id":"http:\/\/www.feuerwehr-daun.de\/wp\/einsatz-231-2021-besetzung-fez\/#primaryimage"},"thumbnailUrl":"https:\/\/www.feuerwehr-daun.de\/wp\/wp-content\/uploads\/2019\/02\/FEZ-Daun-a.jpg","datePublished":"2021-10-17T19:12:44+00:00","dateModified":"2021-10-23T07:42:04+00:00","author":{"@id":"http:\/\/www.feuerwehr-daun.de\/wp\/#\/schema\/person\/d2155f4754f9c8bbdc07fe7e0850e96e"},"breadcrumb":{"@id":"http:\/\/www.feuerwehr-daun.de\/wp\/einsatz-231-2021-besetzung-fez\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.feuerwehr-daun.de\/wp\/einsatz-231-2021-besetzung-fez\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"http:\/\/www.feuerwehr-daun.de\/wp\/einsatz-231-2021-besetzung-fez\/#primaryimage","url":"https:\/\/www.feuerwehr-daun.de\/wp\/wp-content\/uploads\/2019\/02\/FEZ-Daun-a.jpg","contentUrl":"https:\/\/www.feuerwehr-daun.de\/wp\/wp-content\/uploads\/2019\/02\/FEZ-Daun-a.jpg","width":900,"height":400},{"@type":"BreadcrumbList","@id":"http:\/\/www.feuerwehr-daun.de\/wp\/einsatz-231-2021-besetzung-fez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/www.feuerwehr-daun.de\/wp\/"},{"@type":"ListItem","position":2,"name":"Einsatz 234\/2021: Besetzung FEZ"}]},{"@type":"WebSite","@id":"http:\/\/www.feuerwehr-daun.de\/wp\/#website","url":"http:\/\/www.feuerwehr-daun.de\/wp\/","name":"Freiwillige Feuerwehr Daun","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.feuerwehr-daun.de\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"http:\/\/www.feuerwehr-daun.de\/wp\/#\/schema\/person\/d2155f4754f9c8bbdc07fe7e0850e96e","name":"FEZ Daun","url":"https:\/\/www.feuerwehr-daun.de\/wp\/author\/fez-daun\/"}]}},"_links":{"self":[{"href":"https:\/\/www.feuerwehr-daun.de\/wp\/wp-json\/wp\/v2\/posts\/7931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.feuerwehr-daun.de\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.feuerwehr-daun.de\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-daun.de\/wp\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-daun.de\/wp\/wp-json\/wp\/v2\/comments?post=7931"}],"version-history":[{"count":2,"href":"https:\/\/www.feuerwehr-daun.de\/wp\/wp-json\/wp\/v2\/posts\/7931\/revisions"}],"predecessor-version":[{"id":7959,"href":"https:\/\/www.feuerwehr-daun.de\/wp\/wp-json\/wp\/v2\/posts\/7931\/revisions\/7959"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-daun.de\/wp\/wp-json\/wp\/v2\/media\/4567"}],"wp:attachment":[{"href":"https:\/\/www.feuerwehr-daun.de\/wp\/wp-json\/wp\/v2\/media?parent=7931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.feuerwehr-daun.de\/wp\/wp-json\/wp\/v2\/categories?post=7931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.feuerwehr-daun.de\/wp\/wp-json\/wp\/v2\/tags?post=7931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}